{"id":47936,"date":"2026-07-15T08:00:00","date_gmt":"2026-07-15T06:00:00","guid":{"rendered":"https:\/\/www.stb.com.tn\/?p=47936"},"modified":"2026-07-15T08:00:00","modified_gmt":"2026-07-15T06:00:00","slug":"appel-doffres-ao-25-2026-acquisition-de-papier-en-ramettes-sans-impression","status":"publish","type":"post","link":"https:\/\/www.stb.com.tn\/fr\/all-posts\/appel-doffres-ao-25-2026-acquisition-de-papier-en-ramettes-sans-impression\/","title":{"rendered":"Appel d&#8217;offres AO 25-2026 \u00ab Acquisition de papier en ramettes sans impression \u00bb"},"content":{"rendered":"<p class=\"ql-align-center\"><strong style=\"color: black;\">AVIS D\u2019APPEL D\u2019OFFRES<\/strong><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">REF. AO 25-2026<\/strong><\/p>\n<p class=\"ql-align-center\"><strong>&nbsp;<em>\u00ab <\/em>ACQUISITION DE PAPIER EN RAME<\/strong><strong style=\"color: black;\">TTES <\/strong><strong>SANS IMPRESSION<em> \u00bb <\/em><\/strong><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: red;\"><em>&nbsp;<\/em><\/strong><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p><strong style=\"color: black;\">&nbsp;I.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Objet de l\u2019Appel d\u2019Offres :<\/strong><\/p>\n<p class=\"ql-align-justify\">&nbsp;<\/p>\n<p class=\"ql-align-justify\">Le pr\u00e9sent Appel d\u2019offres a pour objet l&#8217;acquisition, par la Soci\u00e9t\u00e9 Tunisienne de Banque (<strong>STB<\/strong>), de papier en ramettes sans impression.<\/p>\n<p class=\"ql-align-justify\">&nbsp;<\/p>\n<p class=\"ql-align-justify\">Cette acquisition porte sur l\u2019article suivant : <\/p>\n<p class=\"ql-align-justify\">&nbsp;<\/p>\n<ul>\n<li class=\"ql-align-justify\">30 000 rames de 500 feuilles de papier extra blanc format A4 (pour impression sur imprimantes laser).<\/li>\n<\/ul>\n<p class=\"ql-align-justify\">&nbsp;<\/p>\n<p><strong style=\"color: black;\">&nbsp;&nbsp;II.&nbsp;&nbsp;Retrait du dossier d\u2019Appel d\u2019Offres :<\/strong><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">Les candidats d\u00e9sirant participer au pr\u00e9sent Appel d\u2019Offres peuvent retirer le cahier des charges aupr\u00e8s de <\/span><strong style=\"color: black;\"><em>la <\/em>Direction Centrale des achats<\/strong><span style=\"color: black;\"> de la Soci\u00e9t\u00e9 Tunisienne de Banque<\/span><strong style=\"color: black;\"><em> <\/em>IMMEUBLE STB MEDV- 1<\/strong><sup style=\"color: black;\"><strong>\u00e8re<\/strong><\/sup><strong style=\"color: black;\"> \u00e9tage &#8211; RUE BORJINE 1073 &#8211; MONTPLAISIR TUNIS<\/strong><span style=\"color: black;\">, contre le versement d\u2019un montant de <\/span><strong style=\"color: black;\">100 DT (Cent dinars Tunisiens) en esp\u00e8ces<\/strong><span style=\"color: black;\"> au compte n\u00b0 <\/span><strong style=\"color: black;\">100 105 126\/8<\/strong><span style=\"color: black;\"> ouvert aupr\u00e8s de notre Agence Centrale, \u00e0 compter de la parution du pr\u00e9sent avis.<\/span><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p><strong style=\"color: black;\">&nbsp;III.&nbsp;&nbsp;Pr\u00e9sentation et envoi de l\u2019offre :<\/strong><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p><span style=\"color: black;\">L\u2019offre doit \u00eatre plac\u00e9e dans une enveloppe appel\u00e9e \u00ab <\/span><strong style=\"color: black;\">Enveloppe Ext\u00e9rieure<\/strong><span style=\"color: black;\"> \u00bb et doit contenir :<\/span><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color: black;\">1.&nbsp;&nbsp;La caution provisoire :&nbsp;<\/strong><\/p>\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<span style=\"color: black;\">Le montant de la caution provisoire est fix\u00e9 \u00e0 : <\/span><strong style=\"color: black;\">3 500 (Trois mille cinq cent) Dinars<\/strong><span style=\"color: black;\"> Tunisiens<\/span><strong style=\"color: black;\">.<\/strong><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color: black;\">2.&nbsp;&nbsp;Les documents administratifs exig\u00e9s par le cahier des charges.<\/strong><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color: black;\">3.&nbsp;&nbsp;L\u2019enveloppe comportant l\u2019offre technique constitu\u00e9 des documents exig\u00e9s par le cahier des charges.<\/strong><\/p>\n<p class=\"ql-align-justify\"><strong style=\"color: black;\">4.&nbsp;&nbsp;L\u2019enveloppe comportant l\u2019offre financi\u00e8re constitu\u00e9 des documents exig\u00e9s par le cahier des charges.<\/strong><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">La caution provisoire, les documents administratifs, l\u2019enveloppe de l\u2019offre technique et l\u2019enveloppe de l\u2019offre financi\u00e8re doivent \u00eatre plac\u00e9s dans une \u00ab <\/span><strong style=\"color: black;\">Enveloppe Ext\u00e9rieure \u00bb<\/strong><span style=\"color: black;\"> ferm\u00e9e et scell\u00e9e. Cette enveloppe ext\u00e9rieure doit porter la mention apparente suivante :<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">A NE PAS OUVRIR<\/strong><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">APPEL D\u2019OFFRES R\u00e9f. AO 25\/2026<\/strong><\/p>\n<p class=\"ql-align-center\"><strong><em>\u00ab <\/em>ACQUISITION DE PAPIER EN RAME<\/strong><strong style=\"color: black;\">TTES <\/strong><strong>SANS IMPRESSION <em>\u00bb <\/em><\/strong><\/p>\n<p class=\"ql-align-center\"><strong>&nbsp;<\/strong><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p><span style=\"color: black;\">L&#8217;enveloppe ext\u00e9rieure doit \u00eatre envoy\u00e9e, sous pli ferm\u00e9, par voie postale en recommand\u00e9, par rapide poste ou par porteur contre d\u00e9charge \u00e0 l\u2019adresse suivante :<\/span><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">SOCIETE TUNISIENNE DE BANQUE<\/strong><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">Bureau d\u2019Ordre Central<\/strong><\/p>\n<p class=\"ql-align-center\"><strong style=\"color: black;\">Rue H\u00e9di Nouira 1001 \u2013 Tunis \u2013 Tunisie<\/strong><\/p>\n<p><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p><strong style=\"color: black;\">&nbsp;IV.&nbsp;&nbsp;Validit\u00e9 et Date limite de r\u00e9ception des offres :<\/strong><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">&nbsp;<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">Le d\u00e9lai pendant lequel les soumissionnaires resteront engag\u00e9s par leurs offres est de<\/span><strong style=\"color: black;\"> <\/strong><span style=\"color: black;\">120 jours, \u00e0 compter du lendemain de la date limite de r\u00e9ception des offres<\/span><strong style=\"color: black;\">, <\/strong><span style=\"color: black;\">fix\u00e9e au<\/span><strong style=\"color: black;\"> Lundi 03 Aout 2026 <\/strong><span style=\"color: black;\">(le cachet du Bureau d\u2019Ordre Central de la STB faisant foi). Toute offre non-conforme aux dispositions \u00e9nonc\u00e9es ci-dessus sera rejet\u00e9e de plein droit.<\/span><\/p>\n<p class=\"ql-align-justify\"><span style=\"color: black;\">Cet avis est publi\u00e9 sur le site web de la Soci\u00e9t\u00e9 Tunisienne de Banque <\/span><a href=\"http:\/\/www.stb.com.tn\/\" rel=\"noopener noreferrer\" target=\"_blank\" style=\"color: black;\"><strong>www.stb.com.tn<\/strong><\/a><strong style=\"color: black;\">.<\/strong><\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVIS D\u2019APPEL D\u2019OFFRES REF. AO 25-2026 &nbsp;\u00ab ACQUISITION DE PAPIER EN RAMETTES SANS IMPRESSION \u00bb &nbsp; &nbsp; &nbsp;I.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Objet de l\u2019Appel d\u2019Offres : &nbsp; Le pr\u00e9sent Appel d\u2019offres a pour objet l&#8217;acquisition, par la Soci\u00e9t\u00e9 Tunisienne de Banque (STB), de papier en ramettes sans impression. &nbsp; Cette acquisition porte sur l\u2019article suivant : &nbsp; 30 000 rames de 500 feuilles de papier extra blanc format A4 (pour impression sur imprimantes laser). &nbsp; &nbsp;&nbsp;II.&nbsp;&nbsp;Retrait du dossier d\u2019Appel d\u2019Offres : &nbsp; Les candidats d\u00e9sirant participer au pr\u00e9sent Appel d\u2019Offres peuvent retirer le cahier des charges aupr\u00e8s de la Direction Centrale des achats de la Soci\u00e9t\u00e9 Tunisienne de Banque IMMEUBLE STB MEDV- 1\u00e8re \u00e9tage &#8211; RUE BORJINE 1073 &#8211; MONTPLAISIR TUNIS, contre le versement d\u2019un montant de 100 DT (Cent dinars Tunisiens) en esp\u00e8ces au compte n\u00b0 100 105 126\/8 ouvert aupr\u00e8s de notre Agence Centrale, \u00e0 compter de la parution du pr\u00e9sent avis. &nbsp; &nbsp;III.&nbsp;&nbsp;Pr\u00e9sentation et envoi de l\u2019offre : &nbsp; L\u2019offre doit \u00eatre plac\u00e9e dans une enveloppe appel\u00e9e \u00ab Enveloppe Ext\u00e9rieure \u00bb et doit contenir : 1.&nbsp;&nbsp;La caution provisoire :&nbsp; \u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Le montant de la caution provisoire est fix\u00e9 \u00e0 : 3 500 (Trois mille cinq cent) Dinars Tunisiens. 2.&nbsp;&nbsp;Les documents administratifs exig\u00e9s [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":38345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Appel d'offres AO 25-2026 \u00ab Acquisition de papier en ramettes sans impression \u00bb","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[128,95],"tags":[],"class_list":["post-47936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-appels-doffres","category-all-posts"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 23:57:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"rttpg_featured_image_url":{"full":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"landscape":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"portraits":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"thumbnail":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-150x150.png",150,150,true],"medium":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-300x181.png",300,181,true],"large":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"1536x1536":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"2048x2048":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"saturnthemes-financebank-full-thumb":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"saturnthemes-financebank-grid-thumb":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-270x163.png",270,163,true],"saturnthemes-financebank-grid-style1":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-370x210.png",370,210,true],"saturnthemes-financebank-grid-style2":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6.png",511,308,false],"saturnthemes-financebank-service-grid":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-370x230.png",370,230,true],"saturnthemes-financebank-staff-grid":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-270x200.png",270,200,true],"rpwe-thumbnail":["https:\/\/www.stb.com.tn\/wp-content\/uploads\/2026\/01\/image-6-45x45.png",45,45,true]},"rttpg_author":{"display_name":"Amira Alouni","author_link":"https:\/\/www.stb.com.tn\/fr\/author\/amira-stb\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/www.stb.com.tn\/fr\/category\/appels-doffres\/\" rel=\"category tag\">Appels d'Offres<\/a> <a href=\"https:\/\/www.stb.com.tn\/fr\/category\/all-posts\/\" rel=\"category tag\">Toutes les Actualit\u00e9s<\/a>","rttpg_excerpt":"AVIS D\u2019APPEL D\u2019OFFRES REF. AO 25-2026 &nbsp;\u00ab ACQUISITION DE PAPIER EN RAMETTES SANS IMPRESSION \u00bb &nbsp; &nbsp; &nbsp;I.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Objet de l\u2019Appel d\u2019Offres : &nbsp; Le pr\u00e9sent Appel d\u2019offres a pour objet l&#8217;acquisition, par la Soci\u00e9t\u00e9 Tunisienne de Banque (STB), de papier en ramettes sans impression. &nbsp; Cette acquisition porte sur l\u2019article suivant : &nbsp; 30 000\u2026","_links":{"self":[{"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/posts\/47936"}],"collection":[{"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/comments?post=47936"}],"version-history":[{"count":1,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/posts\/47936\/revisions"}],"predecessor-version":[{"id":47937,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/posts\/47936\/revisions\/47937"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/media\/38345"}],"wp:attachment":[{"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/media?parent=47936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/categories?post=47936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stb.com.tn\/fr\/wp-json\/wp\/v2\/tags?post=47936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}